{"id":141,"date":"2024-11-20T23:19:01","date_gmt":"2024-11-20T23:19:01","guid":{"rendered":"https:\/\/www.8agaves.com.mx\/contact\/"},"modified":"2025-04-10T12:33:52","modified_gmt":"2025-04-10T12:33:52","slug":"contacto","status":"publish","type":"page","link":"https:\/\/www.8agaves.com.mx\/en\/contacto\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; admin_label=&#8221;row&#8221; _builder_version=&#8221;4.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;82%&#8221; max_width=&#8221;4600px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; custom_padding=&#8221;|||&#8221; border_width_right=&#8221;1px&#8221; border_color_right=&#8221;gcid-e616c3cc-9b70-4acc-8895-2ea70ed53a95&#8243; border_width_right_tablet=&#8221;0px&#8221; border_width_right_phone=&#8221;0px&#8221; border_width_right_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{%22gcid-e616c3cc-9b70-4acc-8895-2ea70ed53a95%22:%91%22border_color_right%22%93}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|3%||40%|false|false&#8221; custom_padding_tablet=&#8221;|3%||40%|false|false&#8221; custom_padding_phone=&#8221;|3%||40%|false|false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p class=\"p1\">Estamos ubicados en Xonacatl\u00e1n, Estado de M\u00e9xico a 25 minutos de Santa Fe, Ciudad de M\u00e9xico y a 15 minutos del Aeropuerto Internaciona de Toluca.<\/p>\n<p class=\"p1\">\u2022 Contacto: 729 100 95 62<\/p>\n<p class=\"p1\"><a href=\"mailto:montserrat@8agaves.com\" target=\"_blank\" rel=\"noopener\">montserrat@8agaves.com<\/a> <br \/><a href=\"mailto:info@8agaves.com\">info@8agaves.com<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 class=\"p1\"><strong>Contactanos<\/strong><\/h1>\n<p class=\"p1\">Recibe atenci\u00f3n personalizada, Uno a Uno, de manera inmediata para asesorarte y que cuentes con toda la informaci\u00f3n disponible para emprender o potencializar tu proyecto con nosotros.<\/p>\n<p>[\/et_pb_text][et_pb_contact_form use_spam_service=&#8221;on&#8221; recaptcha_list=&#8221;inversifikmx|inversifikmx-0&#8243; email=&#8221;montserrat@8agaves.com&#8221; custom_message=&#8221;Has recibido un mensaje desde Inversifik.mx desde Contacto||et_pb_line_break_holder||||et_pb_line_break_holder||El usuario se llama: %%Name%%||et_pb_line_break_holder||Empresa:  %%empresa%%||et_pb_line_break_holder||Codigo postal:  %%codigo-postal%%||et_pb_line_break_holder||Email:  %%Email%%||et_pb_line_break_holder||y el Mensaje:||et_pb_line_break_holder||%%Mensaje%%&#8221; success_message=&#8221;Gracias, en breve te responderemos&#8221; submit_button_text=&#8221;Enviar&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;e7c4dbf1-50a8-4e36-9bf6-6800932d121e&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Nombre completo&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;empresa&#8221; field_title=&#8221;Empresa&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;codigo-postal&#8221; field_title=&#8221;C\u00f3digo postal&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;Email&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Mensaje&#8221; field_title=&#8221;Mensaje&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos ubicados en Xonacatl\u00e1n, Estado de M\u00e9xico a 25 minutos de Santa Fe, Ciudad de M\u00e9xico y a 15 minutos del Aeropuerto Internaciona de Toluca. \u2022 Contacto: 729 100 95 62 montserrat@8agaves.com info@8agaves.comContactanos Recibe atenci\u00f3n personalizada, Uno a Uno, de manera inmediata para asesorarte y que cuentes con toda la informaci\u00f3n disponible para emprender o potencializar tu proyecto con nosotros.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:uagb\/container {\"block_id\":\"ad0b82ab\",\"backgroundType\":\"image\",\"backgroundImageDesktop\":{\"id\":16,\"title\":\"hero-bg\",\"filename\":\"hero-bg.jpg\",\"url\":\"https:\/\/www.8agaves.com.mx\/wp-content\/uploads\/2021\/05\/hero-bg.jpg\",\"link\":\"https:\/\/www.8agaves.com.mx\/hero-bg\/\",\"alt\":\"\",\"author\":\"39\",\"description\":\"\",\"caption\":\"\",\"name\":\"hero-bg\",\"status\":\"inherit\",\"uploadedTo\":0,\"date\":\"2021-05-03T11:23:28.000Z\",\"modified\":\"2021-05-03T11:23:28.000Z\",\"menuOrder\":0,\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"icon\":\"https:\/\/www.8agaves.com.mx\/wp-content\/uploads\/2024\/11\/default.png\",\"dateFormatted\":\"May 3, 2021\",\"nonces\":{\"update\":\"60f8f1fec7\",\"delete\":\"7627172a27\",\"edit\":\"c8c6969e18\"},\"editLink\":\"https:\/\/www.8agaves.com.mx\/wp-admin\/post.php?post=16u0026action=edit\",\"meta\":false,\"authorName\":\"sonalib\",\"authorLink\":\"https:\/\/www.8agaves.com.mx\/wp-admin\/user-edit.php?user_id=39\",\"filesizeInBytes\":135902,\"filesizeHumanReadable\":\"133 KB\",\"context\":\"\",\"height\":1027,\"width\":1920,\"orientation\":\"landscape\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/websitedemos.net\/digital-agency-08\/wp-content\/uploads\/sites\/850\/2021\/05\/hero-bg-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":160,\"width\":300,\"url\":\"https:\/\/websitedemos.net\/digital-agency-08\/wp-content\/uploads\/sites\/850\/2021\/05\/hero-bg-300x160.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":548,\"width\":1024,\"url\":\"https:\/\/websitedemos.net\/digital-agency-08\/wp-content\/uploads\/sites\/850\/2021\/05\/hero-bg-1024x548.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.8agaves.com.mx\/wp-content\/uploads\/2021\/05\/hero-bg.jpg\",\"height\":1027,\"width\":1920,\"orientation\":\"landscape\"}},\"compat\":{\"item\":\"\",\"meta\":\"\"}},\"backgroundAttachmentDesktop\":\"fixed\",\"backgroundAttachmentTablet\":\"scroll\",\"backgroundAttachmentMobile\":\"scroll\",\"backgroundImageColor\":\"var(u002du002dast-global-color-7)\",\"borderStyle\":\"\",\"topPaddingDesktop\":240,\"bottomPaddingDesktop\":120,\"leftPaddingDesktop\":0,\"rightPaddingDesktop\":0,\"topPaddingTablet\":200,\"bottomPaddingTablet\":50,\"leftPaddingTablet\":50,\"rightPaddingTablet\":50,\"topPaddingMobile\":150,\"bottomPaddingMobile\":50,\"leftPaddingMobile\":25,\"rightPaddingMobile\":25,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"overlayType\":\"color\",\"overlayOpacity\":0.85} -->\n<div class=\"wp-block-uagb-container uagb-block-ad0b82ab alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/info-box {\"classMigrate\":true,\"headingAlign\":\"left\",\"headingAlignTablet\":\"left\",\"headingAlignMobile\":\"left\",\"headingColor\":\"var(u002du002dast-global-color-5)\",\"headingTag\":\"h1\",\"headSpace\":0,\"seperatorSpace\":10,\"block_id\":\"08a86b03\",\"seperatorPosition\":\"after_icon\",\"seperatorStyle\":\"solid\",\"seperatorColor\":\"var(u002du002dast-global-color-0)\",\"seperatorWidth\":64,\"seperatorWidthTablet\":64,\"separatorWidthType\":\"px\",\"seperatorThickness\":5,\"ctaBorderColor\":\"\",\"ctaBorderStyle\":\"\",\"showIcon\":false,\"showDesc\":false,\"paddingBtnTop\":10,\"paddingBtnBottom\":10,\"paddingBtnLeft\":14,\"paddingBtnRight\":14,\"headTopMargin\":0,\"headRightMargin\":0,\"headLeftMargin\":0,\"blockTopPadding\":0,\"blockRightPadding\":0,\"blockLeftPadding\":0,\"blockBottomPadding\":0,\"blockTopMargin\":0,\"blockRightMargin\":0,\"blockLeftMargin\":0,\"blockBottomMargin\":0,\"separatorTopMargin\":0,\"separatorRightMargin\":0,\"separatorLeftMargin\":0,\"btnBorderTopWidth\":1,\"btnBorderLeftWidth\":1,\"btnBorderRightWidth\":1,\"btnBorderBottomWidth\":1,\"btnBorderTopLeftRadius\":0,\"btnBorderTopRightRadius\":0,\"btnBorderBottomLeftRadius\":0,\"btnBorderBottomRightRadius\":0,\"btnBorderStyle\":\"solid\",\"btnBorderColor\":\"#333\"} -->\n<div class=\"wp-block-uagb-info-box uagb-block-08a86b03 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-separator\"><\/div><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Contact<\/h1><\/div><\/div><\/div><\/div>\n<!-- \/wp:uagb\/info-box --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"bf596a9d\",\"directionDesktop\":\"row\",\"alignItemsDesktop\":\"stretch\",\"alignItemsTablet\":\"flex-start\",\"backgroundType\":\"color\",\"backgroundSizeTablet\":\"cover\",\"backgroundSizeMobile\":\"cover\",\"backgroundColor\":\"var(u002du002dast-global-color-0)\",\"borderStyle\":\"\",\"topPaddingDesktop\":120,\"bottomPaddingDesktop\":0,\"topPaddingTablet\":50,\"bottomPaddingTablet\":0,\"leftPaddingTablet\":50,\"rightPaddingTablet\":50,\"topPaddingMobile\":0,\"bottomPaddingMobile\":0,\"leftPaddingMobile\":0,\"rightPaddingMobile\":0,\"paddingLink\":false,\"variationSelected\":true,\"rowGapDesktop\":0,\"rowGapMobile\":0,\"columnGapDesktop\":0,\"columnGapTablet\":0,\"isBlockRootParent\":true,\"equalHeight\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-bf596a9d alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"8135cd0c\",\"widthDesktop\":50,\"alignItemsDesktop\":\"flex-start\",\"justifyContentDesktop\":\"flex-start\",\"borderStyle\":\"\",\"topPaddingDesktop\":35,\"bottomPaddingDesktop\":120,\"rightPaddingDesktop\":50,\"topPaddingTablet\":0,\"bottomPaddingTablet\":0,\"leftPaddingTablet\":0,\"rightPaddingTablet\":50,\"topPaddingMobile\":50,\"bottomPaddingMobile\":50,\"leftPaddingMobile\":25,\"rightPaddingMobile\":25,\"paddingLink\":false,\"variationSelected\":true,\"rowGapDesktop\":0,\"columnGapDesktop\":0,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-8135cd0c\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"1b3a60be\",\"classMigrate\":true,\"headingAlignMobile\":\"left\",\"headSpace\":0,\"blockBottomPadding\":40,\"blockBottomPaddingMobile\":20} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1b3a60be\"><h2 class=\"uagb-heading-text\">We are here to help!<\/h2><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/icon-list {\"block_id\":\"52c15154\",\"classMigrate\":true,\"childMigrate\":true,\"parentIcon\":\"\",\"gap\":20,\"inner_gap\":20,\"size\":18,\"fontWeight\":\"700\"} -->\n<div class=\"wp-block-uagb-icon-list uagb-block-52c15154\"><div class=\"uagb-icon-list__wrap\"><!-- wp:uagb\/icon-list-child {\"block_id\":\"ab224c9d\",\"label\":\"1234 N Spring St, Los Angeles, CA 90012\",\"icon\":\"location-dot\",\"label_color\":\"\",\"fromParentIcon\":\"\",\"imageSizeChild\":18} -->\n<div class=\"wp-block-uagb-icon-list-child uagb-block-ab224c9d\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path d=\"M168.3 499.2C116.1 435 0 279.4 0 192C0 85.96 85.96 0 192 0C298 0 384 85.96 384 192C384 279.4 267 435 215.7 499.2C203.4 514.5 180.6 514.5 168.3 499.2H168.3zM192 256C227.3 256 256 227.3 256 192C256 156.7 227.3 128 192 128C156.7 128 128 156.7 128 192C128 227.3 156.7 256 192 256z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">1234 N Spring St, Los Angeles, CA 90012<\/span><\/div>\n<!-- \/wp:uagb\/icon-list-child -->\n\n<!-- wp:uagb\/icon-list-child {\"block_id\":\"a93271a0\",\"label\":\"+1 234 567 890\",\"icon\":\"phone\",\"label_color\":\"\",\"fromParentIcon\":\"\",\"imageSizeChild\":18} -->\n<div class=\"wp-block-uagb-icon-list-child uagb-block-a93271a0\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M511.2 387l-23.25 100.8c-3.266 14.25-15.79 24.22-30.46 24.22C205.2 512 0 306.8 0 54.5c0-14.66 9.969-27.2 24.22-30.45l100.8-23.25C139.7-2.602 154.7 5.018 160.8 18.92l46.52 108.5c5.438 12.78 1.77 27.67-8.98 36.45L144.5 207.1c33.98 69.22 90.26 125.5 159.5 159.5l44.08-53.8c8.688-10.78 23.69-14.51 36.47-8.975l108.5 46.51C506.1 357.2 514.6 372.4 511.2 387z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">+1 234 567 890<\/span><\/div>\n<!-- \/wp:uagb\/icon-list-child --><\/div><\/div>\n<!-- \/wp:uagb\/icon-list -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"b31eef22\",\"classMigrate\":true,\"headingTag\":\"h3\",\"headSpace\":0,\"blockTopPadding\":50,\"blockRightPadding\":0,\"blockLeftPadding\":0,\"blockBottomPadding\":30} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b31eef22\"><h3 class=\"uagb-heading-text\">Follow us<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/social-share {\"classMigrate\":true,\"childMigrate\":true,\"block_id\":\"1f270b3a\",\"align\":\"left\",\"alignTablet\":\"left\",\"alignMobile\":\"left\",\"socials\":[{\"type\":\"facebook\",\"image_icon\":\"icon\",\"icon\":\"fab fa-facebook\",\"image\":\"\",\"icon_color\":\"#3a3a3a\",\"icon_hover_color\":\"\",\"icon_bg_color\":\"\",\"icon_bg_hover_color\":\"\"},{\"type\":\"facebook\",\"image_icon\":\"icon\",\"icon\":\"fab fa-facebook\",\"image\":\"\",\"icon_color\":\"#3a3a3a\",\"icon_hover_color\":\"\",\"icon_bg_color\":\"\",\"icon_bg_hover_color\":\"\"},{\"type\":\"facebook\",\"image_icon\":\"icon\",\"icon\":\"fab fa-facebook\",\"image\":\"\",\"icon_color\":\"#3a3a3a\",\"icon_hover_color\":\"\",\"icon_bg_color\":\"\",\"icon_bg_hover_color\":\"\"}],\"gap\":35,\"gapTablet\":35,\"gapMobile\":35,\"size\":17,\"sizeMobile\":17,\"sizeTablet\":17,\"bgSize\":0,\"bgSizeMobile\":15,\"bgSizeTablet\":15,\"borderRadius\":100,\"borderRadiusTablet\":100,\"borderRadiusMobile\":100,\"iconBgColor\":\"rgba(0,0,0,0.95)\"} -->\n<div class=\"wp-block-uagb-social-share uagb-social-share__outer-wrap uagb-social-share__layout-horizontal uagb-block-1f270b3a\"><!-- wp:uagb\/social-share-child {\"block_id\":\"74500f46\",\"current_url\":\"https:\/\/www.8agaves.com.mx\/contact\/\",\"icon_color\":\"var(u002du002dast-global-color-2)\",\"icon_bg_color\":\"#0270ba00\",\"parentSize\":17,\"parentSizeMobile\":17,\"parentSizeTablet\":17} -->\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-74500f46\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/www.facebook.com\/sharer.php?u=\" tabindex=\"0\" role=\"button\" aria-label=\"facebook\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.8 90.69 226.4 209.3 245V327.7h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.3 482.4 504 379.8 504 256z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n<!-- \/wp:uagb\/social-share-child -->\n\n<!-- wp:uagb\/social-share-child {\"block_id\":\"1cf40db8\",\"type\":\"twitter\",\"current_url\":\"https:\/\/www.8agaves.com.mx\/contact\/\",\"icon\":\"twitter\",\"icon_color\":\"var(u002du002dast-global-color-2)\",\"icon_bg_color\":\"#0270ba00\",\"parentSize\":17,\"parentSizeMobile\":17,\"parentSizeTablet\":17} -->\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-1cf40db8\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/twitter.com\/share?url=\" tabindex=\"0\" role=\"button\" aria-label=\"twitter\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M459.4 151.7c.325 4.548 .325 9.097 .325 13.65 0 138.7-105.6 298.6-298.6 298.6-59.45 0-114.7-17.22-161.1-47.11 8.447 .974 16.57 1.299 25.34 1.299 49.06 0 94.21-16.57 130.3-44.83-46.13-.975-84.79-31.19-98.11-72.77 6.498 .974 12.99 1.624 19.82 1.624 9.421 0 18.84-1.3 27.61-3.573-48.08-9.747-84.14-51.98-84.14-102.1v-1.299c13.97 7.797 30.21 12.67 47.43 13.32-28.26-18.84-46.78-51.01-46.78-87.39 0-19.49 5.197-37.36 14.29-52.95 51.65 63.67 129.3 105.3 216.4 109.8-1.624-7.797-2.599-15.92-2.599-24.04 0-57.83 46.78-104.9 104.9-104.9 30.21 0 57.5 12.67 76.67 33.14 23.72-4.548 46.46-13.32 66.6-25.34-7.798 24.37-24.37 44.83-46.13 57.83 21.12-2.273 41.58-8.122 60.43-16.24-14.29 20.79-32.16 39.31-52.63 54.25z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n<!-- \/wp:uagb\/social-share-child -->\n\n<!-- wp:uagb\/social-share-child {\"block_id\":\"b7462bc0\",\"type\":\"linkedin\",\"current_url\":\"https:\/\/www.8agaves.com.mx\/contact\/\",\"icon\":\"youtube\",\"icon_color\":\"var(u002du002dast-global-color-2)\",\"icon_bg_color\":\"#0270ba00\",\"parentSize\":17,\"parentSizeMobile\":17,\"parentSizeTablet\":17} -->\n<div class=\"wp-block-uagb-social-share-child uagb-ss-repeater uagb-ss__wrapper uagb-block-b7462bc0\"><span class=\"uagb-ss__link\" data-href=\"https:\/\/www.linkedin.com\/shareArticle?url=\" tabindex=\"0\" role=\"button\" aria-label=\"linkedin\"><span class=\"uagb-ss__source-wrap\"><span class=\"uagb-ss__source-icon\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><path d=\"M549.7 124.1c-6.281-23.65-24.79-42.28-48.28-48.6C458.8 64 288 64 288 64S117.2 64 74.63 75.49c-23.5 6.322-42 24.95-48.28 48.6-11.41 42.87-11.41 132.3-11.41 132.3s0 89.44 11.41 132.3c6.281 23.65 24.79 41.5 48.28 47.82C117.2 448 288 448 288 448s170.8 0 213.4-11.49c23.5-6.321 42-24.17 48.28-47.82 11.41-42.87 11.41-132.3 11.41-132.3s0-89.44-11.41-132.3zm-317.5 213.5V175.2l142.7 81.21-142.7 81.2z\"><\/path><\/svg><\/span><\/span><\/span><\/div>\n<!-- \/wp:uagb\/social-share-child --><\/div>\n<!-- \/wp:uagb\/social-share --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"cc11407c\",\"widthDesktop\":50,\"alignItemsDesktop\":\"flex-start\",\"backgroundType\":\"color\",\"backgroundSizeTablet\":\"cover\",\"backgroundSizeMobile\":\"cover\",\"backgroundColor\":\"var(u002du002dast-global-color-5)\",\"borderStyle\":\"\",\"topPaddingDesktop\":50,\"bottomPaddingDesktop\":50,\"leftPaddingDesktop\":50,\"rightPaddingDesktop\":50,\"topPaddingTablet\":30,\"bottomPaddingTablet\":30,\"leftPaddingTablet\":30,\"rightPaddingTablet\":30,\"topPaddingMobile\":50,\"bottomPaddingMobile\":50,\"leftPaddingMobile\":25,\"rightPaddingMobile\":25,\"paddingLink\":false,\"variationSelected\":true,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-cc11407c\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"68cdcc1e\",\"classMigrate\":true,\"headingTag\":\"h3\",\"headSpace\":0,\"blockBottomPadding\":20} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-68cdcc1e\"><h3 class=\"uagb-heading-text\">Send us a message<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/forms {\"block_id\":\"165498b2\",\"formPaddingTop\":0,\"formPaddingRight\":0,\"formPaddingBottom\":0,\"formPaddingLeft\":0,\"formPaddingTopTab\":0,\"formPaddingRightTab\":0,\"formPaddingBottomTab\":0,\"formPaddingLeftTab\":0,\"formPaddingTopMob\":0,\"formPaddingRightMob\":0,\"formPaddingBottomMob\":0,\"formPaddingLeftMob\":0,\"submitButtonText\":\"Send Message\",\"failedMessageTextColor\":\"var(u002du002dast-global-color-2)\",\"afterSubmitToEmail\":\"abc@gmail.com\",\"buttonSize\":\"default\",\"inputborderStyle\":\"\",\"inputborderColor\":\"\",\"labelAlignment\":\"left\",\"successMessageTextColor\":\"var(u002du002dast-global-color-2)\",\"displayLabels\":false,\"inheritFromTheme\":true,\"fieldBorderTopWidth\":1,\"fieldBorderLeftWidth\":1,\"fieldBorderRightWidth\":1,\"fieldBorderBottomWidth\":1,\"fieldBorderTopLeftRadius\":3,\"fieldBorderTopRightRadius\":3,\"fieldBorderBottomLeftRadius\":3,\"fieldBorderBottomRightRadius\":3,\"fieldBorderStyle\":\"solid\",\"fieldBorderColor\":\"#dddddd\",\"checkBoxToggleBorderTopWidth\":1,\"checkBoxToggleBorderLeftWidth\":1,\"checkBoxToggleBorderRightWidth\":1,\"checkBoxToggleBorderBottomWidth\":1,\"checkBoxToggleBorderTopLeftRadius\":3,\"checkBoxToggleBorderTopRightRadius\":3,\"checkBoxToggleBorderBottomLeftRadius\":3,\"checkBoxToggleBorderBottomRightRadius\":3,\"checkBoxToggleBorderStyle\":\"solid\",\"checkBoxToggleBorderColor\":\"#BDBDBD\",\"btnBorderTopLeftRadius\":3,\"btnBorderTopRightRadius\":3,\"btnBorderBottomLeftRadius\":3,\"btnBorderBottomRightRadius\":3,\"variationSelected\":true} -->\n<div class=\"wp-block-uagb-forms uagb-forms__outer-wrap uagb-block-165498b2 uagb-forms__default-btn\"><form class=\"uagb-forms-main-form\" method=\"post\" autocomplete=\"on\" name=\"uagb-form-165498b2\"><!-- wp:uagb\/forms-name {\"block_id\":\"209ba4f7\",\"name\":\"First Name\",\"placeholder\":\"First Name\",\"autocomplete\":\"given-name\",\"className\":\"uag-col-2\"} -->\n<div class=\"wp-block-uagb-forms-name uagb-forms-name-wrap uagb-forms-field-set uagb-block-209ba4f7 uag-col-2\"><div class=\"uagb-forms-name-label  uagb-forms-input-label\" id=\"209ba4f7\">First Name<\/div><input type=\"text\" placeholder=\"First Name\" class=\"uagb-forms-name-input uagb-forms-input\" name=\"209ba4f7\" autocomplete=\"given-name\"\/><\/div>\n<!-- \/wp:uagb\/forms-name -->\n\n<!-- wp:uagb\/forms-name {\"block_id\":\"63d24976\",\"name\":\"Last Name\",\"placeholder\":\"Last Name\",\"autocomplete\":\"family-name\",\"className\":\"uag-col-2\"} -->\n<div class=\"wp-block-uagb-forms-name uagb-forms-name-wrap uagb-forms-field-set uagb-block-63d24976 uag-col-2\"><div class=\"uagb-forms-name-label  uagb-forms-input-label\" id=\"63d24976\">Last Name<\/div><input type=\"text\" placeholder=\"Last Name\" class=\"uagb-forms-name-input uagb-forms-input\" name=\"63d24976\" autocomplete=\"family-name\"\/><\/div>\n<!-- \/wp:uagb\/forms-name -->\n\n<!-- wp:uagb\/forms-email {\"block_id\":\"0b416125\",\"placeholder\":\"Email Address\"} -->\n<div class=\"wp-block-uagb-forms-email uagb-forms-email-wrap uagb-forms-field-set uagb-block-0b416125\"><div class=\"uagb-forms-email-label  uagb-forms-input-label\" id=\"0b416125\">Email<\/div><input type=\"email\" class=\"uagb-forms-email-input uagb-forms-input\" placeholder=\"Email Address\" name=\"0b416125\" autocomplete=\"email\"\/><\/div>\n<!-- \/wp:uagb\/forms-email -->\n\n<!-- wp:uagb\/forms-email {\"block_id\":\"63539be1\",\"placeholder\":\"Subject\"} -->\n<div class=\"wp-block-uagb-forms-email uagb-forms-email-wrap uagb-forms-field-set uagb-block-63539be1\"><div class=\"uagb-forms-email-label  uagb-forms-input-label\" id=\"63539be1\">Email<\/div><input type=\"email\" class=\"uagb-forms-email-input uagb-forms-input\" placeholder=\"Subject\" name=\"63539be1\" autocomplete=\"email\"\/><\/div>\n<!-- \/wp:uagb\/forms-email -->\n\n<!-- wp:uagb\/forms-textarea {\"block_id\":\"ef4f10d9\",\"textareaRequired\":true,\"placeholder\":\"Your Message\"} -->\n<div class=\"wp-block-uagb-forms-textarea uagb-forms-textarea-wrap uagb-forms-field-set uagb-block-ef4f10d9\"><div class=\"uagb-forms-textarea-label required uagb-forms-input-label\" id=\"ef4f10d9\">Message<\/div><textarea required class=\"uagb-forms-textarea-input uagb-forms-input\" rows=\"4\" placeholder=\"Your Message\" name=\"ef4f10d9\" autocomplete=\"off\"><\/textarea><\/div>\n<!-- \/wp:uagb\/forms-textarea --><div class=\"uagb-forms-form-hidden-data\"><input type=\"hidden\" class=\"uagb_forms_form_label\" value=\"Spectra Form\"\/><input type=\"hidden\" class=\"uagb_forms_form_id\" value=\"uagb-form-165498b2\"\/><\/div><div class=\"uagb-form-reacaptcha-error-165498b2\"><\/div><div class=\"uagb-forms-main-submit-button-wrap wp-block-button\"><button class=\"uagb-forms-main-submit-button wp-block-button__link\"><div class=\"uagb-forms-main-submit-button-text\">Send Message<\/div><\/button><\/div><\/form><div class=\"uagb-forms-success-message-165498b2 uagb-forms-submit-message-hide\"><span>The form has been submitted successfully!<\/span><\/div><div class=\"uagb-forms-failed-message-165498b2 uagb-forms-submit-message-hide\"><span>There has been some error while submitting the form. Please verify all form fields again.<\/span><\/div><\/div>\n<!-- \/wp:uagb\/forms --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"52cc8b92\",\"innerContentWidth\":\"alignfull\",\"alignItemsDesktop\":\"stretch\",\"backgroundType\":\"color\",\"backgroundSizeTablet\":\"cover\",\"backgroundSizeMobile\":\"cover\",\"backgroundColor\":\"var(u002du002dast-global-color-5)\",\"borderStyle\":\"\",\"topPaddingDesktop\":0,\"bottomPaddingDesktop\":0,\"leftPaddingDesktop\":0,\"rightPaddingDesktop\":0,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"equalHeight\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-52cc8b92 alignfull uagb-is-root-container\"><!-- wp:uagb\/google-map {\"block_id\":\"76394e28\",\"address\":\"1234 N Spring St, Los Angeles, CA 90012\",\"height\":380,\"heightTablet\":380,\"heightMobile\":380,\"zoom\":16} \/--><\/div>\n<!-- \/wp:uagb\/container -->","_et_gb_content_width":"","_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-141","page","type-page","status-publish","hentry"],"aioseo_notices":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"et-pb-post-main-image":false,"et-pb-post-main-image-fullwidth":false,"et-pb-portfolio-image":false,"et-pb-portfolio-module-image":false,"et-pb-portfolio-image-single":false,"et-pb-gallery-module-image-portrait":false,"et-pb-post-main-image-fullwidth-large":false,"et-pb-image--responsive--desktop":false,"et-pb-image--responsive--tablet":false,"et-pb-image--responsive--phone":false},"uagb_author_info":{"display_name":"act.lopez83@gmail.com","author_link":"https:\/\/www.8agaves.com.mx\/en\/author\/act-lopez83gmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Estamos ubicados en Xonacatl\u00e1n, Estado de M\u00e9xico a 25 minutos de Santa Fe, Ciudad de M\u00e9xico y a 15 minutos del Aeropuerto Internaciona de Toluca. \u2022 Contacto: 729 100 95 62 montserrat@8agaves.com info@8agaves.comContactanos Recibe atenci\u00f3n personalizada, Uno a Uno, de manera inmediata para asesorarte y que cuentes con toda la informaci\u00f3n disponible para emprender o&hellip;","_links":{"self":[{"href":"https:\/\/www.8agaves.com.mx\/en\/wp-json\/wp\/v2\/pages\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.8agaves.com.mx\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.8agaves.com.mx\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.8agaves.com.mx\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.8agaves.com.mx\/en\/wp-json\/wp\/v2\/comments?post=141"}],"version-history":[{"count":11,"href":"https:\/\/www.8agaves.com.mx\/en\/wp-json\/wp\/v2\/pages\/141\/revisions"}],"predecessor-version":[{"id":277433,"href":"https:\/\/www.8agaves.com.mx\/en\/wp-json\/wp\/v2\/pages\/141\/revisions\/277433"}],"wp:attachment":[{"href":"https:\/\/www.8agaves.com.mx\/en\/wp-json\/wp\/v2\/media?parent=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}